{"id":490,"date":"2012-06-21T02:41:46","date_gmt":"2012-06-21T02:41:46","guid":{"rendered":"http:\/\/www.plantillas-powerpoint.com\/blog\/?p=490"},"modified":"2012-06-21T02:41:46","modified_gmt":"2012-06-21T02:41:46","slug":"crear-un-diagrama-de-embudo-en-powerpoint","status":"publish","type":"post","link":"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/","title":{"rendered":"Crear un diagrama de embudo en PowerPoint"},"content":{"rendered":"<p>Microsoft PowerPoint es una herramienta muy \u00fatil para crear presentaciones (de hecho es la m\u00e1s utilizada en todo el mundo), que nos permite hacerlas m\u00e1s atractivas a\u00f1adiendo im\u00e1genes, gr\u00e1ficos, v\u00eddeos y <a href=\"https:\/\/www.plantillas-powerpoint.com\/blog\/categoria\/diagramas\/\">diagramas<\/a>. Los <strong>diagramas de embudo en PowerPoint<\/strong> nos permiten realizar una explicaci\u00f3n m\u00e1s intuitiva a la audiencia.<\/p>\n<p>Hoy vamos a explicar c\u00f3mo <strong>crear un diagrama de embudo en PowerPoint<\/strong>.<\/p>\n<p style=\"text-align: center;\">\u00a0<img decoding=\"async\" src=\"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-content\/uploads\/2012\/06\/funnel-diagram2-450x370.jpg\" alt=\"\" \/><\/p>\n<p>En primer lugar tenemos que dibujar algunas formas. Vamos a necesitar un tri\u00e1ngulo, un rect\u00e1ngulo y dos c\u00edrculos como podemos ver a continuaci\u00f3n:<\/p>\n<p style=\"text-align: center;\">\u00a0<img decoding=\"async\" src=\"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-content\/uploads\/2012\/06\/funnel-diagram-450x358.jpg\" alt=\"\" \/><\/p>\n<p>Puede que tengamos que modificar el tama\u00f1o de las formas y modificar la l\u00ednea exterior para que se ajuste completamente. Tambi\u00e9n podemos a\u00f1adir sombras o cambiar el color de acuerdo a la <a href=\"http:\/\/presentacion.org\" target=\"_blank\">presentaci\u00f3n de Microsoft Power Point<\/a>.<\/p>\n<p>Si necesitamos un diagrama de embudo m\u00e1s complejo s\u00f3lo tenemos que crear m\u00e1s formas y mantenerlos en orden para que se vea bien.<\/p>\n<p>En las pr\u00f3ximas semanas mostraremos c\u00f3mo crear buenos diagramas de <strong>embudo en 3D para PowerPoint<\/strong> con variaciones de esta t\u00e9cnica.<\/p>\n","protected":false},"excerpt":{"rendered":"<a href=\"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-content\/plugins\/thumbnail-for-excerpts\/tfe_no_thumb.png\" class=\"alignleft wp-post-image tfe\" alt=\"\" title=\"\" \/><\/a><p>Microsoft PowerPoint es una herramienta muy \u00fatil para crear presentaciones (de hecho es la m\u00e1s utilizada en todo el mundo), que nos permite hacerlas m\u00e1s atractivas a\u00f1adiendo im\u00e1genes, gr\u00e1ficos, v\u00eddeos y diagramas. Los diagramas de embudo en PowerPoint nos permiten realizar una explicaci\u00f3n m\u00e1s intuitiva a la audiencia. Hoy vamos a explicar c\u00f3mo crear un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[220],"tags":[224,226,221,151,225,6,8],"class_list":["post-490","post","type-post","status-publish","format-standard","hentry","category-diagramas","tag-3d","tag-diagrama","tag-diagramas-2","tag-disenos","tag-embudo","tag-formas-2","tag-powerpoint"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crear un diagrama de embudo en PowerPoint<\/title>\n<meta name=\"description\" content=\"Microsoft PowerPoint es una herramienta muy \u00fatil para crear presentaciones (de hecho es la m\u00e1s utilizada en todo el mundo), que nos permite hacerlas m\u00e1s atractivas a\u00f1adiendo im\u00e1genes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crear un diagrama de embudo en PowerPoint\" \/>\n<meta property=\"og:description\" content=\"Microsoft PowerPoint es una herramienta muy \u00fatil para crear presentaciones (de hecho es la m\u00e1s utilizada en todo el mundo), que nos permite hacerlas m\u00e1s atractivas a\u00f1adiendo im\u00e1genes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/\" \/>\n<meta property=\"og:site_name\" content=\"Plantillas Power Point\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-21T02:41:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-content\/uploads\/2012\/06\/funnel-diagram2-450x370.jpg\" \/>\n<meta name=\"author\" content=\"jose\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/\",\"url\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/\",\"name\":\"Crear un diagrama de embudo en PowerPoint\",\"isPartOf\":{\"@id\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-content\/uploads\/2012\/06\/funnel-diagram2-450x370.jpg\",\"datePublished\":\"2012-06-21T02:41:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/#\/schema\/person\/011717f7599b27367460e5e4492d881d\"},\"description\":\"Microsoft PowerPoint es una herramienta muy \u00fatil para crear presentaciones (de hecho es la m\u00e1s utilizada en todo el mundo), que nos permite hacerlas m\u00e1s atractivas a\u00f1adiendo im\u00e1genes\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/#primaryimage\",\"url\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-content\/uploads\/2012\/06\/funnel-diagram2-450x370.jpg\",\"contentUrl\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-content\/uploads\/2012\/06\/funnel-diagram2-450x370.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/#website\",\"url\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/\",\"name\":\"Plantillas Power Point\",\"description\":\"Presentaciones, fondos de diapositivas y temas para Power Point Gratis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/#\/schema\/person\/011717f7599b27367460e5e4492d881d\",\"name\":\"jose\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/05ca6c96675c1428ed0d92c44429df421a7c24eeae34ae86db920e727eb965d1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/05ca6c96675c1428ed0d92c44429df421a7c24eeae34ae86db920e727eb965d1?s=96&d=mm&r=g\",\"caption\":\"jose\"},\"url\":\"https:\/\/www.plantillas-powerpoint.com\/blog\/author\/jose\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crear un diagrama de embudo en PowerPoint","description":"Microsoft PowerPoint es una herramienta muy \u00fatil para crear presentaciones (de hecho es la m\u00e1s utilizada en todo el mundo), que nos permite hacerlas m\u00e1s atractivas a\u00f1adiendo im\u00e1genes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/","og_locale":"es_ES","og_type":"article","og_title":"Crear un diagrama de embudo en PowerPoint","og_description":"Microsoft PowerPoint es una herramienta muy \u00fatil para crear presentaciones (de hecho es la m\u00e1s utilizada en todo el mundo), que nos permite hacerlas m\u00e1s atractivas a\u00f1adiendo im\u00e1genes","og_url":"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/","og_site_name":"Plantillas Power Point","article_published_time":"2012-06-21T02:41:46+00:00","og_image":[{"url":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-content\/uploads\/2012\/06\/funnel-diagram2-450x370.jpg","type":"","width":"","height":""}],"author":"jose","twitter_misc":{"Escrito por":"jose","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/","url":"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/","name":"Crear un diagrama de embudo en PowerPoint","isPartOf":{"@id":"https:\/\/www.plantillas-powerpoint.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/#primaryimage"},"image":{"@id":"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/#primaryimage"},"thumbnailUrl":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-content\/uploads\/2012\/06\/funnel-diagram2-450x370.jpg","datePublished":"2012-06-21T02:41:46+00:00","author":{"@id":"https:\/\/www.plantillas-powerpoint.com\/blog\/#\/schema\/person\/011717f7599b27367460e5e4492d881d"},"description":"Microsoft PowerPoint es una herramienta muy \u00fatil para crear presentaciones (de hecho es la m\u00e1s utilizada en todo el mundo), que nos permite hacerlas m\u00e1s atractivas a\u00f1adiendo im\u00e1genes","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.plantillas-powerpoint.com\/blog\/crear-un-diagrama-de-embudo-en-powerpoint\/#primaryimage","url":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-content\/uploads\/2012\/06\/funnel-diagram2-450x370.jpg","contentUrl":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-content\/uploads\/2012\/06\/funnel-diagram2-450x370.jpg"},{"@type":"WebSite","@id":"https:\/\/www.plantillas-powerpoint.com\/blog\/#website","url":"https:\/\/www.plantillas-powerpoint.com\/blog\/","name":"Plantillas Power Point","description":"Presentaciones, fondos de diapositivas y temas para Power Point Gratis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.plantillas-powerpoint.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.plantillas-powerpoint.com\/blog\/#\/schema\/person\/011717f7599b27367460e5e4492d881d","name":"jose","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.plantillas-powerpoint.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/05ca6c96675c1428ed0d92c44429df421a7c24eeae34ae86db920e727eb965d1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05ca6c96675c1428ed0d92c44429df421a7c24eeae34ae86db920e727eb965d1?s=96&d=mm&r=g","caption":"jose"},"url":"https:\/\/www.plantillas-powerpoint.com\/blog\/author\/jose\/"}]}},"_links":{"self":[{"href":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-json\/wp\/v2\/posts\/490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-json\/wp\/v2\/comments?post=490"}],"version-history":[{"count":4,"href":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-json\/wp\/v2\/posts\/490\/revisions"}],"predecessor-version":[{"id":497,"href":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-json\/wp\/v2\/posts\/490\/revisions\/497"}],"wp:attachment":[{"href":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-json\/wp\/v2\/media?parent=490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-json\/wp\/v2\/categories?post=490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plantillas-powerpoint.com\/blog\/wp-json\/wp\/v2\/tags?post=490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}